{"id":3,"count":21,"description":"","link":"http:\/\/viewguru.com\/view-guru\/category\/california\/","name":"California","slug":"california","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"http:\/\/viewguru.com\/view-guru\/wp-json\/wp\/v2\/categories\/3","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/viewguru.com\/view-guru\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"http:\/\/viewguru.com\/view-guru\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"http:\/\/viewguru.com\/view-guru\/wp-json\/wp\/v2\/posts?categories=3"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}