{"id":43,"count":1,"description":"","link":"http:\/\/viewguru.com\/view-guru\/category\/australia\/","name":"Australia","slug":"australia","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"http:\/\/viewguru.com\/view-guru\/wp-json\/wp\/v2\/categories\/43","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/viewguru.com\/view-guru\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"http:\/\/viewguru.com\/view-guru\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"http:\/\/viewguru.com\/view-guru\/wp-json\/wp\/v2\/posts?categories=43"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}